{"id":71,"count":2,"description":"","link":"https:\/\/kubraselegance.com\/sr\/%d1%83%d1%80%d1%83%d0%bd-%d0%ba%d0%b0%d1%82%d0%b5%d0%b3%d0%be%d1%80%d0%b8\/%d0%b4%d0%b2%d0%be%d0%b4%d0%b5%d0%bb%d0%bd%d0%b8-%d1%81%d0%b5%d1%82\/","name":"\u0434\u0432\u043e\u0434\u0435\u043b\u043d\u0438 \u0441\u0435\u0442","slug":"%d0%b4%d0%b2%d0%be%d0%b4%d0%b5%d0%bb%d0%bd%d0%b8-%d1%81%d0%b5%d1%82","taxonomy":"product_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/kubraselegance.com\/sr\/wp-json\/wp\/v2\/product_cat\/71","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kubraselegance.com\/sr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/kubraselegance.com\/sr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/kubraselegance.com\/sr\/wp-json\/wp\/v2\/product?product_cat=71"}],"curies":[{"name":"\u0412\u041f","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}